{"id":97259,"date":"2021-05-27T13:41:03","date_gmt":"2021-05-27T18:41:03","guid":{"rendered":"https:\/\/graziamagazine.com\/mx\/?post_type=articles&#038;p=97259"},"modified":"2021-05-27T14:52:04","modified_gmt":"2021-05-27T19:52:04","slug":"ya-puedes-ocultar-los-me-gusta-en-instagram","status":"publish","type":"articles","link":"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/","title":{"rendered":"Ya puedes ocultar los &#8220;me gusta&#8221; en Instagram"},"content":{"rendered":"<p>Pareciera que este d\u00eda nunca iba a llegar, pero lleg\u00f3. Aunque Instagram hab\u00eda anunciado hace ya tiempo que se podr\u00edan dejar de ver los &#8220;me gusta&#8221; de las publicaciones de la red social, la opci\u00f3n se hab\u00eda ido retrasando pero ya es una realidad.<\/p>\n<p>Desde hoy la App ya ha comenzado a implementar esta funci\u00f3n, que poco a poco de manera progresiva llegar\u00e1 a todos los usuarios, eso s\u00ed, <strong>ser\u00e1 decisi\u00f3n de cada usuario elegir si s\u00ed o si no la activa.\u00a0<\/strong><\/p>\n<p>Si decides activar la opci\u00f3n, solo t\u00fa (esta vez s\u00ed) y podr\u00e1s ver el n\u00famero de likes de tus posteos fijos o el n\u00famero de reproducciones de tus videos, mientras que el resto de usuarios no ver\u00e1 nada en tu perfil o tus posteos. Lo malo es que, no podr\u00e1s activar esta opci\u00f3n por defecto y que se aplique a todo tu perfil, si no que tendr\u00e1s que ir una por una en tus publicaciones eligi\u00e9ndolas y activ\u00e1ndolo. Suponemos que en futuras actualizaciones esta opci\u00f3n tambi\u00e9n ir\u00e9 mejorando.<\/p>\n<h3>\u00bfC\u00f3mo activarlo?<\/h3>\n<p>Bien, para ocultar los me gusta o reproducciones de tus contenidos, una vez dentro de tu perfil elige la publicaci\u00f3n, pulsa el bot\u00f3n de los tres puntos que se sit\u00faa a la derecha y se desfliegar\u00e1 el men\u00fa de opciones. Entre todas ella <strong>elige &#8220;ocultar recuento de me gusta&#8221;,<\/strong> y una vez activado se har\u00e1 la magia y los dem\u00e1s no ver\u00e1n nada.<\/p>\n<p>Finalmente Instagram ha tomado la decisi\u00f3n de que el usuario pueda elegir si activarlo o no porque, &#8220;<em>si bien algunas personas pensaron que era positivo tener oculto este recuento o n\u00famero, a otras les gustar\u00eda seguir viendo este dato para poder identificar tendencias y contenidos m\u00e1s populares en\u00a0<\/em><span class=\"markxqcugfvkx\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\"><em>Instagram<\/em>&#8220;<\/span>.<\/p>\n<p>Esta nueva opci\u00f3n <strong>se suma a otras herramientas lanzadas recientemente<\/strong> que buscan brindar a las personas m\u00e1s poder sobre su experiencia en\u00a0<span class=\"markxqcugfvkx\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">Instagram<\/span>, como la administraci\u00f3n del tiempo, la funci\u00f3n Restringir, la herramienta Silenciar y una nueva forma de filtrar solicitudes de mensajes abusivos en Direct. La actualizaci\u00f3n tambi\u00e9n es parte de una serie de caracter\u00edsticas similares disponibles en Facebook, como las herramientas del Feed, con las cuales el usuario podr\u00e1 seleccionar qui\u00e9n puede comentar en sus publicaciones, eligiendo ver el contenido de amigos cercanos y p\u00e1ginas favoritas.<\/p>\n<p><strong><em>*IMAGEN: Getty Images<\/em><\/strong><\/p>\n","protected":false},"author":11653,"featured_media":97266,"template":"","format":"standard","categories":[114],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.5 (Yoast SEO v20.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ya puedes ocultar los &quot;me gusta&quot; en Instagram | Grazia M\u00e9xico y Latinoam\u00e9rica<\/title>\n<meta name=\"description\" content=\"La \u00faltima actualizaci\u00f3n de la App finalmente va a permitir que nadie conozca los likes y te decimos c\u00f3mo podr\u00e1s activarlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ya puedes ocultar los &quot;me gusta&quot; en Instagram\" \/>\n<meta property=\"og:description\" content=\"La \u00faltima actualizaci\u00f3n de la App finalmente va a permitir que nadie conozca los likes y te decimos c\u00f3mo podr\u00e1s activarlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/\" \/>\n<meta property=\"og:site_name\" content=\"Grazia M\u00e9xico y Latinoam\u00e9rica\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-27T19:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2021\/05\/WhatsApp-Image-2021-05-27-at-2.10.13-PM.jpeg?fit=1280%2C853\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/\",\"url\":\"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/\",\"name\":\"Ya puedes ocultar los \\\"me gusta\\\" en Instagram | Grazia M\u00e9xico y Latinoam\u00e9rica\",\"isPartOf\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\"},\"datePublished\":\"2021-05-27T18:41:03+00:00\",\"dateModified\":\"2021-05-27T19:52:04+00:00\",\"description\":\"La \u00faltima actualizaci\u00f3n de la App finalmente va a permitir que nadie conozca los likes y te decimos c\u00f3mo podr\u00e1s activarlo.\",\"breadcrumb\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/graziamagazine.com\/mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ya puedes ocultar los &#8220;me gusta&#8221; en Instagram\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\",\"url\":\"https:\/\/graziamagazine.com\/mx\/\",\"name\":\"Grazia M\u00e9xico y Latinoam\u00e9rica\",\"description\":\"Grazia es moda, belleza y noticias  de actualidad \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ya puedes ocultar los \"me gusta\" en Instagram | Grazia M\u00e9xico y Latinoam\u00e9rica","description":"La \u00faltima actualizaci\u00f3n de la App finalmente va a permitir que nadie conozca los likes y te decimos c\u00f3mo podr\u00e1s activarlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/","og_locale":"es_MX","og_type":"article","og_title":"Ya puedes ocultar los \"me gusta\" en Instagram","og_description":"La \u00faltima actualizaci\u00f3n de la App finalmente va a permitir que nadie conozca los likes y te decimos c\u00f3mo podr\u00e1s activarlo.","og_url":"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/","og_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","article_modified_time":"2021-05-27T19:52:04+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2021\/05\/WhatsApp-Image-2021-05-27-at-2.10.13-PM.jpeg?fit=1280%2C853","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/","url":"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/","name":"Ya puedes ocultar los \"me gusta\" en Instagram | Grazia M\u00e9xico y Latinoam\u00e9rica","isPartOf":{"@id":"https:\/\/graziamagazine.com\/mx\/#website"},"datePublished":"2021-05-27T18:41:03+00:00","dateModified":"2021-05-27T19:52:04+00:00","description":"La \u00faltima actualizaci\u00f3n de la App finalmente va a permitir que nadie conozca los likes y te decimos c\u00f3mo podr\u00e1s activarlo.","breadcrumb":{"@id":"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/graziamagazine.com\/mx\/articles\/ya-puedes-ocultar-los-me-gusta-en-instagram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/graziamagazine.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Ya puedes ocultar los &#8220;me gusta&#8221; en Instagram"}]},{"@type":"WebSite","@id":"https:\/\/graziamagazine.com\/mx\/#website","url":"https:\/\/graziamagazine.com\/mx\/","name":"Grazia M\u00e9xico y Latinoam\u00e9rica","description":"Grazia es moda, belleza y noticias  de actualidad ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","distributor_original_site_url":"https:\/\/graziamagazine.com\/mx","push-errors":false,"_links":{"self":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles\/97259"}],"collection":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles"}],"about":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/types\/articles"}],"author":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/users\/11653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media\/97266"}],"wp:attachment":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media?parent=97259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/categories?post=97259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}