{"id":139168,"date":"2024-07-11T18:52:51","date_gmt":"2024-07-11T23:52:51","guid":{"rendered":"https:\/\/graziamagazine.com\/mx\/?post_type=articles&#038;p=139168"},"modified":"2024-07-11T18:55:22","modified_gmt":"2024-07-11T23:55:22","slug":"shakira-encendera-la-final-de-la-copa-america-2024","status":"publish","type":"articles","link":"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/","title":{"rendered":"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024"},"content":{"rendered":"<p><span style=\"font-weight: 400\"><strong>Shakira<\/strong> har\u00e1 historia nuevamente al presentarse en el show de medio tiempo de la final de la <strong>Copa Am\u00e9rica 2024<\/strong>, programada para el <strong>domingo 14 de julio<\/strong> en el Hard Rock Stadium de Miami, Florida.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Este evento &#8211; en el que se enfrenta su pa\u00eds natal, <strong>Colombia, contra Argentina<\/strong> &#8211; promete tener todo el entretenimiento que los latinos necesitan en esta final, a\u00f1adiendo m\u00fasica y folklore al ambiente futbol\u00edstico.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Shakira sigue fusionando el esp\u00edritu del f\u00fatbol con la energ\u00eda de la m\u00fasica latina. Su legado comenz\u00f3 con <em><strong>Hips Don\u2019t Lie<\/strong><\/em>, en Alemania 2006, continu\u00f3 con <em><strong>Waka Waka<\/strong> <\/em>en el Mundial de Sud\u00e1frica 2010, y sigui\u00f3 con <em><strong>La La La<\/strong><\/em> en el Mundial de Brasil 2014. Ahora, con su m\u00e1s reciente sencillo <em><strong>Punter\u00eda<\/strong><\/em>, la cantante de Barranquilla regresa para hacer vibrar a los asistentes del torneo de selecciones de Am\u00e9rica.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><em>Punter\u00eda<\/em>, parte de su nuevo \u00e1lbum <strong>Las Mujeres Ya No Lloran<\/strong>, ha sido seleccionado como la banda sonora oficial de la Copa Am\u00e9rica.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cLa Copa Am\u00e9rica es el evento de f\u00fatbol m\u00e1s importante del a\u00f1o, y sabemos que esta canci\u00f3n ser\u00e1 el sonido del verano para los fan\u00e1ticos de todo el mundo. Es el poder de nuestra cultura y de nuestra m\u00fasica\u201d, dijo Shakira.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Frente a una audiencia de 65,000 fans del f\u00fatbol, Shakira promete un espect\u00e1culo inolvidable en el Hard Rock Stadium, conocido por albergar eventos de gran magnitud como Super Bowls y conciertos de artistas de renombre mundial como Beyonc\u00e9, U2, The Rolling Stones y Madonna.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cShakira es una extraordinaria estrella sudamericana que ha deslumbrado al mundo entero. Sus canciones se cantan y bailan en todos los rincones del planeta, convirtiendo su arte en un fen\u00f3meno global que cruza fronteras y que disfrutan millones de personas. Estamos seguros de que su actuaci\u00f3n en el escenario de la Copa Am\u00e9rica USA 2024 potenciar\u00e1 el mensaje de sana pasi\u00f3n y de unidad a trav\u00e9s del deporte\u201d, dijo Alejandro Dom\u00ednguez, presidente de la Conmebol, a trav\u00e9s de un comunicado de prensa.<\/span><\/p>\n","protected":false},"author":11628,"featured_media":122476,"template":"","format":"standard","categories":[12483],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.5 (Yoast SEO v20.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024 | Grazia M\u00e9xico y Latinoam\u00e9rica<\/title>\n<meta name=\"description\" content=\"Shakira har\u00e1 historia nuevamente al presentarse en el show de medio tiempo de la final de la Copa Am\u00e9rica 2024, programada para el domingo 14 de julio en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024\" \/>\n<meta property=\"og:description\" content=\"Shakira har\u00e1 historia nuevamente al presentarse en el show de medio tiempo de la final de la Copa Am\u00e9rica 2024, programada para el domingo 14 de julio en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Grazia M\u00e9xico y Latinoam\u00e9rica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T23:55:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/03\/Captura-de-Pantalla-2023-03-02-a-las-9.36.12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1256\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/\",\"url\":\"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/\",\"name\":\"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024 | Grazia M\u00e9xico y Latinoam\u00e9rica\",\"isPartOf\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\"},\"datePublished\":\"2024-07-11T23:52:51+00:00\",\"dateModified\":\"2024-07-11T23:55:22+00:00\",\"description\":\"Shakira har\u00e1 historia nuevamente al presentarse en el show de medio tiempo de la final de la Copa Am\u00e9rica 2024, programada para el domingo 14 de julio en\",\"breadcrumb\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/graziamagazine.com\/mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\",\"url\":\"https:\/\/graziamagazine.com\/mx\/\",\"name\":\"Grazia M\u00e9xico y Latinoam\u00e9rica\",\"description\":\"Grazia es moda, belleza y noticias  de actualidad \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024 | Grazia M\u00e9xico y Latinoam\u00e9rica","description":"Shakira har\u00e1 historia nuevamente al presentarse en el show de medio tiempo de la final de la Copa Am\u00e9rica 2024, programada para el domingo 14 de julio en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/","og_locale":"es_MX","og_type":"article","og_title":"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024","og_description":"Shakira har\u00e1 historia nuevamente al presentarse en el show de medio tiempo de la final de la Copa Am\u00e9rica 2024, programada para el domingo 14 de julio en","og_url":"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/","og_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","article_modified_time":"2024-07-11T23:55:22+00:00","og_image":[{"width":1256,"height":844,"url":"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/03\/Captura-de-Pantalla-2023-03-02-a-las-9.36.12.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/","url":"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/","name":"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024 | Grazia M\u00e9xico y Latinoam\u00e9rica","isPartOf":{"@id":"https:\/\/graziamagazine.com\/mx\/#website"},"datePublished":"2024-07-11T23:52:51+00:00","dateModified":"2024-07-11T23:55:22+00:00","description":"Shakira har\u00e1 historia nuevamente al presentarse en el show de medio tiempo de la final de la Copa Am\u00e9rica 2024, programada para el domingo 14 de julio en","breadcrumb":{"@id":"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/graziamagazine.com\/mx\/articles\/shakira-encendera-la-final-de-la-copa-america-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/graziamagazine.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Shakira encender\u00e1 la final de la Copa Am\u00e9rica 2024"}]},{"@type":"WebSite","@id":"https:\/\/graziamagazine.com\/mx\/#website","url":"https:\/\/graziamagazine.com\/mx\/","name":"Grazia M\u00e9xico y Latinoam\u00e9rica","description":"Grazia es moda, belleza y noticias  de actualidad ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","distributor_original_site_url":"https:\/\/graziamagazine.com\/mx","push-errors":false,"_links":{"self":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles\/139168"}],"collection":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles"}],"about":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/types\/articles"}],"author":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/users\/11628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media\/122476"}],"wp:attachment":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media?parent=139168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/categories?post=139168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}