{"id":138400,"date":"2024-06-24T12:57:49","date_gmt":"2024-06-24T17:57:49","guid":{"rendered":"https:\/\/graziamagazine.com\/mx\/?post_type=articles&#038;p=138400"},"modified":"2024-07-23T18:49:17","modified_gmt":"2024-07-23T23:49:17","slug":"la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico","status":"publish","type":"articles","link":"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/","title":{"rendered":"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico"},"content":{"rendered":"<p>La semana de la <strong>Alta Costura en Par\u00eds<\/strong>, normalmente un epicentro de creatividad y glamour, este a\u00f1o ha encontrado un desaf\u00edo en mantener su habitual relevancia para los dise\u00f1adores.<\/p>\n<p>Coincidiendo con el a\u00f1o de los <strong>Juegos Ol\u00edmpicos, Maria Grazia Chiuri<\/strong>, directora creativa de <strong>Dior<\/strong>, sinti\u00f3 una conexi\u00f3n especial con este evento global.<\/p>\n<p>As\u00ed, el desfile de <strong>Alta Costura Dior oto\u00f1o-invierno 2024\/2025<\/strong> emergi\u00f3 como una plataforma ideal para fusionar ropa deportiva con alta costura, a trav\u00e9s de innovadores experimentos y, m\u00e1s significativamente, para rendir homenaje a las mujeres atletas.<\/p>\n<div class=\"content-gallery\"><div class=\"gallery-placeholder\"><div class=\"spinner\"><\/div><\/div><span class=\"gallery-pagination\"><\/span><div id=\"gallery-1\" class=\"gallery galleryid-138400 gallery-columns- gallery-size-\"><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.02.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.02.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.02-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.02-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.02-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.02-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.05.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.05.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.05-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.05-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.05-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.05-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.07.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.07.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.07-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.07-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.07-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.07-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.08.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.08.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.08-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.08-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.08-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.08-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.09.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.09.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.09-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.09-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.09-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.09-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.11.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.11.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.11-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.11-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.11-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.11-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><\/div><\/div>\n<p>Estas mujeres, desde la antig\u00fcedad hasta la actualidad, han enfrentado y superado prejuicios y obst\u00e1culos, buscando un lugar de igualdad en las competiciones deportivas y el reconocimiento de sus cuerpos con dignidad atl\u00e9tica.<\/p>\n<blockquote><p>Sorprendentemente, la ropa deportiva se convirti\u00f3 en protagonista en su versi\u00f3n m\u00e1s lujosa, adornada con plumas o cristales. &#8220;Esta colecci\u00f3n es una oportunidad extraordinaria para Chiuri de entrelazar alta costura, ropa deportiva, clasicismo, rebeli\u00f3n, energ\u00eda colectiva y, sobre todo, el valor pol\u00edtico del cuerpo femenino&#8221;, explic\u00f3 la casa de moda. &#8220;Afirma el poder experimental y reflexivo de la investigaci\u00f3n que define las acciones de la alta costura, y su capacidad para repensar las formas de un femenino que es tanto delicado como poderoso, capaz de actuar a la par que los hombres, aunque de manera diferente&#8221;.<\/p>\n<div class=\"content-gallery\"><div class=\"gallery-placeholder\"><div class=\"spinner\"><\/div><\/div><span class=\"gallery-pagination\"><\/span><div id=\"gallery-2\" class=\"gallery galleryid-138400 gallery-columns- gallery-size-\"><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.13.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.13.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.13-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.13-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.13-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.13-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.14.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.14.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.14-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.14-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.14-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.14-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.18.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.18.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.18-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.18-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.18-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.18-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.20.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.20.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.20-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.20-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.20-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.20-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.23.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.23.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.23-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.23-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.23-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.23-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><\/div><\/div><\/blockquote>\n<p>El cuerpo, siempre central en el mundo de la alta costura, adquiri\u00f3 una relevancia a\u00fan mayor en esta pasarela. Para lograrlo, Chiuri comenz\u00f3 con el peplos, una forma primaria del <strong>vestido griego<\/strong>, conocido por su capacidad de moldear y ser moldeado por el cuerpo.<\/p>\n<p>En esta narrativa, un material inusual para la alta costura tom\u00f3 el protagonismo: el jersey. En la pasarela, se alternaron siluetas vaporosas en tonos blancos o met\u00e1licos, gr\u00e1ciles y esenciales, envolviendo el cuerpo y protegi\u00e9ndolo con sutiles &#8220;armaduras&#8221; doradas.<\/p>\n<div class=\"content-gallery\"><div class=\"gallery-placeholder\"><div class=\"spinner\"><\/div><\/div><span class=\"gallery-pagination\"><\/span><div id=\"gallery-3\" class=\"gallery galleryid-138400 gallery-columns- gallery-size-\"><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.25.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.25.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.25-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.25-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.25-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.25-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.28.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.28.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.28-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.28-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.28-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.28-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.34.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.34.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.34-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.34-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.34-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.34-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.40.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.40.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.40-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.40-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.40-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.40-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.41.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.41.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.41-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.41-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.41-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.41-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.44.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.44.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.44-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.44-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.44-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.44-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.47.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.47.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.47-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.47-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.47-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.47-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><\/div><\/div>\n<p>Modernas camisetas de tirantes adornadas con aplicaciones que formaban casi un mosaico embellec\u00edan a\u00fan m\u00e1s los conjuntos, con drapeados y plisados modelados alrededor del cuerpo de manera escultural o relajada, evocando los cl\u00e1sicos vestidos de diosa.<\/p>\n<p>Este enfoque no solo celebra la fuerza y resistencia de las mujeres atletas, sino que tambi\u00e9n reimagina la moda como un espacio inclusivo y empoderador.<\/p>\n<div class=\"content-gallery\"><div class=\"gallery-placeholder\"><div class=\"spinner\"><\/div><\/div><span class=\"gallery-pagination\"><\/span><div id=\"gallery-4\" class=\"gallery galleryid-138400 gallery-columns- gallery-size-\"><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.50.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.50.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.50-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.50-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.50-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.50-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.54.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.54.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.54-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.54-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.54-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.54-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.57.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.57.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.57-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.57-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.57-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.57-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.59.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.59.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.59-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.59-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.59-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.59-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.01.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.01.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.01-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.01-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.01-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.01-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><figure class=\"gallery-item\"><div class=\"gallery-icon landscape\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"1084\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.05.png\" class=\"lazy\" alt=\"\" srcset=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.05.png 696w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.05-289x450.png 289w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.05-657x1024.png 657w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.05-400x623.png 400w, https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.46.05-138x215.png 138w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/figure><\/div><\/div>\n<p>La colecci\u00f3n de Chiuri desaf\u00eda las normas tradicionales de la alta costura, integrando elementos de ropa deportiva de una manera que resalta tanto la belleza est\u00e9tica como la funcionalidad pr\u00e1ctica.<\/p>\n<p>En un a\u00f1o marcado por los Juegos Ol\u00edmpicos, Dior ha logrado capturar el esp\u00edritu del deporte y la alta moda en una sinfon\u00eda visual que celebra la igualdad y la dignidad del cuerpo femenino.<\/p>\n<p><em><strong>*IMAGEN: Dior<\/strong><\/em><\/p>\n","protected":false},"author":28953,"featured_media":138426,"template":"","format":"standard","categories":[4],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.5 (Yoast SEO v20.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico<\/title>\n<meta name=\"description\" content=\"La nueva colecci\u00f3n Alta Costura de Dior reinterpreta con la elegancia el savoir-faire de la alta costura, invitaban a las mujeres a perseguir sus sue\u00f1os con determinaci\u00f3n y confianza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico\" \/>\n<meta property=\"og:description\" content=\"La nueva colecci\u00f3n Alta Costura de Dior reinterpreta con la elegancia el savoir-faire de la alta costura, invitaban a las mujeres a perseguir sus sue\u00f1os con determinaci\u00f3n y confianza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/\" \/>\n<meta property=\"og:site_name\" content=\"Grazia M\u00e9xico y Latinoam\u00e9rica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T23:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12-1-e1719252381176.png\" \/>\n\t<meta property=\"og:image:width\" content=\"695\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/\",\"url\":\"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/\",\"name\":\"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico\",\"isPartOf\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\"},\"datePublished\":\"2024-06-24T17:57:49+00:00\",\"dateModified\":\"2024-07-23T23:49:17+00:00\",\"description\":\"La nueva colecci\u00f3n Alta Costura de Dior reinterpreta con la elegancia el savoir-faire de la alta costura, invitaban a las mujeres a perseguir sus sue\u00f1os con determinaci\u00f3n y confianza.\",\"breadcrumb\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/graziamagazine.com\/mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\",\"url\":\"https:\/\/graziamagazine.com\/mx\/\",\"name\":\"Grazia M\u00e9xico y Latinoam\u00e9rica\",\"description\":\"Grazia es moda, belleza y noticias  de actualidad \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico","description":"La nueva colecci\u00f3n Alta Costura de Dior reinterpreta con la elegancia el savoir-faire de la alta costura, invitaban a las mujeres a perseguir sus sue\u00f1os con determinaci\u00f3n y confianza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/","og_locale":"es_MX","og_type":"article","og_title":"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico","og_description":"La nueva colecci\u00f3n Alta Costura de Dior reinterpreta con la elegancia el savoir-faire de la alta costura, invitaban a las mujeres a perseguir sus sue\u00f1os con determinaci\u00f3n y confianza.","og_url":"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/","og_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","article_modified_time":"2024-07-23T23:49:17+00:00","og_image":[{"width":695,"height":437,"url":"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2024\/06\/Captura-de-Pantalla-2024-06-24-a-las-11.45.12-1-e1719252381176.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/","url":"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/","name":"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico","isPartOf":{"@id":"https:\/\/graziamagazine.com\/mx\/#website"},"datePublished":"2024-06-24T17:57:49+00:00","dateModified":"2024-07-23T23:49:17+00:00","description":"La nueva colecci\u00f3n Alta Costura de Dior reinterpreta con la elegancia el savoir-faire de la alta costura, invitaban a las mujeres a perseguir sus sue\u00f1os con determinaci\u00f3n y confianza.","breadcrumb":{"@id":"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/graziamagazine.com\/mx\/articles\/la-alta-costura-se-reinventa-dior-y-el-espiritu-olimpico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/graziamagazine.com\/mx\/"},{"@type":"ListItem","position":2,"name":"La Alta Costura se reinventa: Dior y el esp\u00edritu ol\u00edmpico"}]},{"@type":"WebSite","@id":"https:\/\/graziamagazine.com\/mx\/#website","url":"https:\/\/graziamagazine.com\/mx\/","name":"Grazia M\u00e9xico y Latinoam\u00e9rica","description":"Grazia es moda, belleza y noticias  de actualidad ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","distributor_original_site_url":"https:\/\/graziamagazine.com\/mx","push-errors":false,"_links":{"self":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles\/138400"}],"collection":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles"}],"about":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/types\/articles"}],"author":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/users\/28953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media\/138426"}],"wp:attachment":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media?parent=138400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/categories?post=138400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}