{"id":126285,"date":"2023-06-14T10:03:08","date_gmt":"2023-06-14T15:03:08","guid":{"rendered":"https:\/\/graziamagazine.com\/mx\/?post_type=articles&#038;p=126285"},"modified":"2023-06-14T10:24:54","modified_gmt":"2023-06-14T15:24:54","slug":"dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano","status":"publish","type":"articles","link":"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/","title":{"rendered":"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano"},"content":{"rendered":"<p>Los motivos, c\u00f3digos y colores de la casa italiana <strong>Dolce &amp; Gabbana<\/strong>, la han convertido en una l\u00ednea de lujo reconocible en cualquier rinc\u00f3n del mundo.<\/p>\n<p>La est\u00e9tica neobarroca, la iconograf\u00eda cl\u00e1sica y los estampados, han jugado un rol imprescindible dentro de cada colecci\u00f3n de la firma y es tiempo de dar la bienvenida al verano con una nueva colaboraci\u00f3n junto a <strong>Pelayo D\u00edaz.<\/strong><\/p>\n<figure id=\"attachment_126290\" aria-describedby=\"caption-attachment-126290\" style=\"width: 805px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-126290\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/06\/DG_SpecialCollection_PelayoDiaz_2023-5.jpeg?w=805\" alt=\"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano\" width=\"805\" height=\"1024\" \/><figcaption id=\"caption-attachment-126290\" class=\"wp-caption-text\">Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano<\/figcaption><\/figure>\n<p>Estilista, bloguero, dise\u00f1ador de moda, escritor y colaborador de televisi\u00f3n espa\u00f1ol que se ha hecho de un nombre gracias a su blog <strong>&#8220;Katelovesme\u201d<\/strong> y que adem\u00e1s, fue uno de los primeros influencers en abrirse paso en la era digital con un estilo autentico y leal a su esencia.<\/p>\n<p>No es extra\u00f1o que Dolce &amp; Gabbana busque siempre ir un paso por delante y en esta ocasi\u00f3n la marca une fuerzas con Pelayo para la creaci\u00f3n de una colecci\u00f3n que evoca \u00e9xito rotundo durante esta temporada.<\/p>\n<figure id=\"attachment_126295\" aria-describedby=\"caption-attachment-126295\" style=\"width: 814px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-126295\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/06\/DG_SpecialCollection_PelayoDiaz_2023-10.jpeg?w=814\" alt=\"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano\" width=\"814\" height=\"1024\" \/><figcaption id=\"caption-attachment-126295\" class=\"wp-caption-text\">Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano<\/figcaption><\/figure>\n<blockquote>\n<div dir=\"ltr\">\n<div lang=\"EN-GB\">\n<div>\n<div>\n<div>\n<div>\n<p align=\"center\"><span lang=\"ES-MX\">&#8220;Pelayo y Dolce &amp; Gabbana da vida a una colecci\u00f3n especial inspirada en los recuerdos de infancia, sus <\/span><span lang=\"ES-MX\">lugares m\u00e1s queridos y las sensaciones que le acompa\u00f1aron a lo largo de su carrera, desde su juventud hasta <\/span><span lang=\"ES-MX\">sus estudios de moda&#8221;, comenta D&amp;G.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<div dir=\"ltr\">\n<div lang=\"EN-GB\">\n<p style=\"text-align: left\" align=\"center\">La colecci\u00f3n gira en torno a 5 conceptos que muestran los recuerdos del influencer espa\u00f1ol traducidos en estampados y colores que forman parte de los archivos de la <em>maison<\/em>. Dentro de esta l\u00ednea se encuentran desde pijamas a camisas, bermudas o batas de seda habotai que saltan de la cama a la calle y se convertir\u00e1n en las piezas protagonistas de los looks favoritos de los prescriptores de estilo este verano.<\/p>\n<figure id=\"attachment_126286\" aria-describedby=\"caption-attachment-126286\" style=\"width: 804px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-126286\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/06\/DG_SpecialCollection_PelayoDiaz_2023-1.jpeg?w=804\" alt=\"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano\" width=\"804\" height=\"1024\" \/><figcaption id=\"caption-attachment-126286\" class=\"wp-caption-text\">Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano<\/figcaption><\/figure>\n<p style=\"text-align: left\" align=\"center\">&#8220;Las Tzas y platos de porcelana en forma de caleidoscopio que hacen alusi\u00f3n a la dimensi\u00f3n \u00edntima y familiar del desayuno en casa; las conchas multiformes recuerdan las playas escondidas de Asturias; coloridos paisajes decoran las puertas del gran armario de la casa familiar de Pelayo en Oviedo; las postales de Ribadesella celebran la belleza de esta villa marinera y sus casas de indianos; la devoci\u00f3n popular a la Virgen de Covadonga aparece en la estampa en blanco y negro&#8221;, describe la firma.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-126297 size-large\" src=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/06\/DG_SpecialCollection_PelayoDiaz_2023-12.jpeg?w=813\" alt=\"\" width=\"813\" height=\"1024\" \/><\/p>\n<p style=\"text-align: left\" align=\"center\">La exclusividad y el maximalismo motivan al lujo silencioso y al &#8220;old money aesthetic&#8221; que durante los \u00faltimos meses ha sido reconocido a nivel mundial. Los art\u00edculos y piezas\u00a0 disponibles est\u00e1n en pre-order en la web de Dolce&amp;Gabbana y en sus flagship stores de Mil\u00e1n, Madrid, Puerto Ban\u00fas, Londres y Miami.<\/p>\n<p style=\"text-align: left\" align=\"center\"><em><strong>*IMAGEN: Cortes\u00eda Dolce &amp; Gabbana<\/strong><\/em><\/p>\n<\/div>\n<div lang=\"EN-GB\">\n<p align=\"center\">\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":28953,"featured_media":126293,"template":"","format":"standard","categories":[4],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.5 (Yoast SEO v20.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano<\/title>\n<meta name=\"description\" content=\"Dolce &amp; Gabbana le da la bienvenida al verano con su nueva colecci\u00f3n de lujo en colaboraci\u00f3n con Pelayo D\u00edaz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano\" \/>\n<meta property=\"og:description\" content=\"Dolce &amp; Gabbana le da la bienvenida al verano con su nueva colecci\u00f3n de lujo en colaboraci\u00f3n con Pelayo D\u00edaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/\" \/>\n<meta property=\"og:site_name\" content=\"Grazia M\u00e9xico y Latinoam\u00e9rica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T15:24:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/06\/DG_SpecialCollection_PelayoDiaz_2023-8.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"807\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/\",\"url\":\"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/\",\"name\":\"Dolce & Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano\",\"isPartOf\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\"},\"datePublished\":\"2023-06-14T15:03:08+00:00\",\"dateModified\":\"2023-06-14T15:24:54+00:00\",\"description\":\"Dolce & Gabbana le da la bienvenida al verano con su nueva colecci\u00f3n de lujo en colaboraci\u00f3n con Pelayo D\u00edaz\",\"breadcrumb\":{\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/graziamagazine.com\/mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/graziamagazine.com\/mx\/#website\",\"url\":\"https:\/\/graziamagazine.com\/mx\/\",\"name\":\"Grazia M\u00e9xico y Latinoam\u00e9rica\",\"description\":\"Grazia es moda, belleza y noticias  de actualidad \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dolce & Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano","description":"Dolce & Gabbana le da la bienvenida al verano con su nueva colecci\u00f3n de lujo en colaboraci\u00f3n con Pelayo D\u00edaz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/","og_locale":"es_MX","og_type":"article","og_title":"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano","og_description":"Dolce & Gabbana le da la bienvenida al verano con su nueva colecci\u00f3n de lujo en colaboraci\u00f3n con Pelayo D\u00edaz","og_url":"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/","og_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","article_modified_time":"2023-06-14T15:24:54+00:00","og_image":[{"url":"https:\/\/graziamagazine.com\/mx\/wp-content\/uploads\/sites\/13\/2023\/06\/DG_SpecialCollection_PelayoDiaz_2023-8.jpeg","width":1024,"height":807,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/","url":"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/","name":"Dolce & Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano","isPartOf":{"@id":"https:\/\/graziamagazine.com\/mx\/#website"},"datePublished":"2023-06-14T15:03:08+00:00","dateModified":"2023-06-14T15:24:54+00:00","description":"Dolce & Gabbana le da la bienvenida al verano con su nueva colecci\u00f3n de lujo en colaboraci\u00f3n con Pelayo D\u00edaz","breadcrumb":{"@id":"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/graziamagazine.com\/mx\/articles\/dolce-gabbana-x-pelayo-diaz-una-coleccion-de-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/graziamagazine.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Dolce &amp; Gabbana x Pelayo D\u00edaz: Una colecci\u00f3n de Verano"}]},{"@type":"WebSite","@id":"https:\/\/graziamagazine.com\/mx\/#website","url":"https:\/\/graziamagazine.com\/mx\/","name":"Grazia M\u00e9xico y Latinoam\u00e9rica","description":"Grazia es moda, belleza y noticias  de actualidad ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/graziamagazine.com\/mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Grazia M\u00e9xico y Latinoam\u00e9rica","distributor_original_site_url":"https:\/\/graziamagazine.com\/mx","push-errors":false,"_links":{"self":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles\/126285"}],"collection":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/articles"}],"about":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/types\/articles"}],"author":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/users\/28953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media\/126293"}],"wp:attachment":[{"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/media?parent=126285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graziamagazine.com\/mx\/wp-json\/wp\/v2\/categories?post=126285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}