{"id":175264,"date":"2024-03-22T12:25:03","date_gmt":"2024-03-22T11:25:03","guid":{"rendered":"https:\/\/graziamagazine.com\/es\/?post_type=articles&#038;p=175264"},"modified":"2024-03-22T12:34:07","modified_gmt":"2024-03-22T11:34:07","slug":"haus-labs-by-lady-gaga-llega-a-espana","status":"publish","type":"articles","link":"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/","title":{"rendered":"Haus Labs by Lady Gaga llega a Espa\u00f1a"},"content":{"rendered":"<p>\u00bfEres de las que vives pegada a las tendencias y los nuevos lanzamientos? Perfecto porque est\u00e1s de enhorabuena ya que una de las marcas m\u00e1s esperadas por fin llega al mercado espa\u00f1ol. Se trata de Haus Labs, la marca creada por Lady Gaga y que lleva alrededor de un a\u00f1o disponible en Grazia Reino Unido, y que cuenta con una gama de productos de maquillaje art\u00edstico de calidad, innovadores, con una alta tecnolog\u00eda detr\u00e1s y formulada con ingredientes cuidadosamente seleccionados.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-175267 size-full\" src=\"https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/sephora_spain-e1711107239846.jpg\" alt=\"\" width=\"1068\" height=\"1057\" srcset=\"https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/sephora_spain-e1711107239846.jpg 1068w, https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/sephora_spain-e1711107239846-300x297.jpg 300w, https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/sephora_spain-e1711107239846-1024x1013.jpg 1024w, https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/sephora_spain-e1711107239846-768x760.jpg 768w, https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/sephora_spain-e1711107239846-400x396.jpg 400w, https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/sephora_spain-e1711107239846-155x153.jpg 155w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/p>\n<p>No te preocupes porque ya no tendr\u00e1s que aprovechar tus viajes a Londres para hacerte con sus productos, porque desde hoy 22 de marzo est\u00e1 en pre-venta en al App de Sephora Espa\u00f1a, y desde el pr\u00f3ximo 26 de marzo lo har\u00e1 de manera exclusiva en las tiendas online y f\u00edsicas de Sephora en Europa.<\/p>\n<h3>Nuestros favoritos que queremos ya<\/h3>\n<p><strong>Base de maquillaje Triclone Skintech Foundation<\/strong><\/p>\n<p>Es un e\u0301xito viral masivo en TikTok con ma\u0301s de 9.700 millones de visitas. <span class=\"markcchi6frb9\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">HAUS<\/span>\u00a0<span class=\"mark36hj7vshd\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">LAB<\/span>S celebra todos los niveles de habilidad arti\u0301stica y todas las edades, formas, taman\u0303os, etnias, ge\u0301neros, identidades y orientaciones sexuales. Los productos\u00a0<span class=\"markcchi6frb9\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">HAUS<\/span>\u00a0<span class=\"mark36hj7vshd\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">LAB<\/span>S se crean con amabilidad siendo veganos TM.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i.ebayimg.com\/images\/g\/V2gAAOSwboBlCl-X\/s-l1600.jpg\" alt=\"Haus Labs By Lady Gaga Triclone Skin Tech Foundation full size no box \u2013 Web Oficial del CF Talavera de la Reina\" \/><\/p>\n<p>Su precio es de 49,99 \u20ac, solo en Sephora<\/p>\n<p><strong>La brocha Foundation Brush<\/strong><\/p>\n<p>Una lujosa brocha de maquillaje disen\u0303ada para crear, pulir y difuminar el maquillaje a la perfeccio\u0301n, con control y facilidad, gracias a sus cerdas sinte\u0301ticas ultrasuaves y densas.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/uc9782e4050e475fd8aa324de346.previews.dropboxusercontent.com\/p\/thumb\/ACP3b4ZintTLg3hgMHke0FmlHPbbgP28kuVxhp0YdBnf00egOe0YVkfGyYN2JZdYj7Dgx07XNdH_kk0XDb7W9GFa5_9WuBlEg7tCxTMQA6LQeYJRwTEwbi3WMcQuhofTU56jnLEGlO7VSTDUAN4cW8BfgNXQl92JaUSmSnit946EsRERnEoGCxJjNqbHbWHY6jl4LVuAZ517nLI-c9xqh8n2icFw8ltsp3ijpSV5cN3XWo-eDQ85z2iuhViPSfHAPLraJykjR0uELA-u3VQBr4aJJy1Mw41FvTJ3Zm_vbPe61-N0T8HdYr7bYvS1ffL_XthQHgF7oaEplurBlL7W8wx0V23IzDTJgiYYlOFti2weAw\/p.jpeg\" alt=\"840073501536_1.jpg\" \/><\/p>\n<p>Su precio es de 40,99 \u20ac, solo en Sephora<\/p>\n<p aria-hidden=\"true\"><strong>Pigmentos l\u00edquidos Hy-Power Pigment Paints<\/strong><\/p>\n<p aria-hidden=\"true\">Nos encantan porque estos concentrados color los podemos usar en ojos, labios, mejillas y hasta en el cuerpo. Un b\u00e1sico que no puede faltar en tu neceser, si adem\u00e1s quiere crear beauty looks dram\u00e1ticos. 12 tonos mate, opaco, cubriente y brillante, impregnados de escualeno y a\u0301cido hialuro\u0301nico de origen vegetal.<\/p>\n<p aria-hidden=\"true\"><img decoding=\"async\" src=\"https:\/\/www.hauslabs.com\/cdn\/shop\/products\/qicnnfuda.jpg?v=1688674060\" alt=\"Hy-Power Pigment Paint | Hauslabs.com - HAUS LABS BY LADY GAGA\" \/><\/p>\n<p>Su precio es de 25,99 \u20ac, solo en Sephora<\/p>\n<p><strong>Polvos sueltos difuminadores Bio Blurring Loose Powder<\/strong><\/p>\n<p>\u00bfCon que\u0301 suen\u0303a tu cutis? Con unos polvos sueltos, limpios, que cuiden la piel, que se difuminen, que controlen los brillos y que fijen el maquillaje. \u00a1Deseo cumplido con esta pequen\u0303a joya, unos polvos universales, infundidos con el complejo\u00a0<span class=\"markcchi6frb9\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">Haus<\/span>Tech PoweredTM, con a\u0301rnica fermentada y escualeno de origen vegetal!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/uc5e7e730cc1a08da1570af6aeef.previews.dropboxusercontent.com\/p\/thumb\/ACPZ6WrA9mAxnz7syjfHizme_xvGLkAL81Akic1Htr3N410W2wbBPeKM4GnPcZU52dvbYWjs3NEUokvRN0D4HEjfR3q7oZ-PtZvxhBEcIAzUsdpFbmyfB0oPBc09PyJh06-itFKizAS7ZAxza7pGnMGwPmG5edB5WxPOUjaoLbMTOEh8E87WsV2vtnHNkmqO-iRmbVKVK7NnZqbnz7_GNYRopFIEEwgCNM3CJEbvVpL7IUkSzJZIxFuf_cdIAfk1copmmd62ftPjdBb-8rRI_fiDT6rS4-P3FOMpK1RTHLgqFcPOTOR7BdNtOBqc7k4mJGvROLCCIkKIkPOFOt1nMFjbeuDL9MlM8SDxuMz8G0rb9w\/p.jpeg\" alt=\"840073503868_1.jpg\" \/><\/p>\n<p>Su precio es de 41,99 \u20ac, solo en Sephora<\/p>\n<p><strong>Aceite labial PhD Hybrid Lip Oil<\/strong><\/p>\n<p>Tan de moda, los aceites labiales son el nuevo b\u00e1sico de la belleza y en Haus Labs no falta ning\u00fan color, desde el transparente para todos los momentos del d\u00eda, al m\u00e1s\u00a0<em>Shockin Pink, Orange me\u0301canique o Gourmand grenadine<\/em>&#8230; Estos aceites labiales est\u00e1n recubiertos con una fo\u0301rmula superbrillante y no pegajosa (con cola\u0301geno vegano y aceite de higo chumbo), los\u00a0<span class=\"mark36hj7vshd\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">lab<\/span>ios quedan alisados, hidratados e impregnados de color.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i.pinimg.com\/736x\/14\/73\/7f\/14737f031a4e09da55438f6c79e6f2aa.jpg\" alt=\"Haus Labs New PHD Hybrid Lip Oil Stain That Customises To Your Personal pH in 2024 | Lip oil, Lip hydration, Oil stains\" \/><\/p>\n<p>Su precio es de 25,99 \u20ac, solo en Sephora<\/p>\n<p><strong>Optic Intensity Eco Eyeliner\u00a0<\/strong><\/p>\n<p>Los eyeliner de Haus Labs est\u00e1n creados con una fo\u0301rmula de larga duracio\u0301n que tambi\u00e9n es resistente al agua.\u00a0 Este delineador posee un nu\u0301cleo 100% bio-celulosa, hecho de fibras de papel reciclado &#8211; no de pla\u0301stico., cuenta con vitamina E y aceite de arga\u0301n, que garantizan su f\u00e1cil aplicacio\u0301n impecable. Su aplicaci\u00f3n es muy cremosa y adem\u00e1s est\u00e1n superpigmentados con base kajal, lo que hace que se deslice s\u00faper f\u00e1cil en el p\u00e1rpado gracias a su punta de gel.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/uc3959ee062f0aa9fa0b01fc17fa.previews.dropboxusercontent.com\/p\/thumb\/ACMaLPFiOvgJPSENk7D-vnYqtOZXSDr-_AZZxEu-8jWNfDgC313XH7NNmC6oxRrlP3c8ucSZ8jRrlYDCOPkAaZ7eYMBDHhszRZr6lmveFNnNwV-mbji8PTsAGmVV2EMOyafzVK6ROPkHW7bp5h0X2VGF6uMtoccA7ZQFBxDnCQw-EDzoeyJ2fPzXym_S2D656ZaSSLhcX07xXoRlOZ3-GvgWU8OnWbTDVZSQ0C9LeRDIvHig4qKvH8EHKIMhLkQEJivat9djWV_7JsfGfOYZcTtWmyvAOzoO43SwG2TNGtcopJQQ2ORx9_bCiQsAW0QPV0047lJVTcq2md8quiuAEhs8IaCeh4cwDlOIiCQz_YeKQ0nUGE9aqVuxK-lirUFwPHi6IgNlRNoYFMeU9CpB3qui0khX_aIaqXcuyHSa7ViQrkYYvGj9_moWDuK8Ak6VemNXwl1ParTem1zXVBiNQgJ5mU_LS5PAZ4flQb5Kk01MFx6wRSuxRDrPlehGZrWvEIpRoQM0QlWoi85xcNa7Ohrm\/p.jpeg\" alt=\"Shot_05_Eye_Liner_Marketing_Hero_0291.jpg\" \/><\/p>\n<p>Su precio es de 24,99 \u20ac, solo en Sephora<\/p>\n<p><em>*Im\u00e1genes: cortes\u00eda<\/em><\/p>\n","protected":false},"author":11653,"featured_media":175265,"template":"","format":"standard","categories":[7],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.5 (Yoast SEO v20.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Haus Labs by Lady Gaga llega a Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Tras el lanzamiento el an\u0303o pasado en Sephora UK, la marca de belleza estara\u0301 disponible en exclusiva en Sephora Europa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haus Labs by Lady Gaga llega a Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Tras el lanzamiento el an\u0303o pasado en Sephora UK, la marca de belleza estara\u0301 disponible en exclusiva en Sephora Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Grazia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T11:34:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/img-copia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/\",\"url\":\"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/\",\"name\":\"Haus Labs by Lady Gaga llega a Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\/\/graziamagazine.com\/es\/#website\"},\"datePublished\":\"2024-03-22T11:25:03+00:00\",\"dateModified\":\"2024-03-22T11:34:07+00:00\",\"description\":\"Tras el lanzamiento el an\u0303o pasado en Sephora UK, la marca de belleza estara\u0301 disponible en exclusiva en Sephora Europa.\",\"breadcrumb\":{\"@id\":\"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/graziamagazine.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Haus Labs by Lady Gaga llega a Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/graziamagazine.com\/es\/#website\",\"url\":\"https:\/\/graziamagazine.com\/es\/\",\"name\":\"Grazia\",\"description\":\"Moda, belleza, celebrities, estilo de vida...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/graziamagazine.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Haus Labs by Lady Gaga llega a Espa\u00f1a","description":"Tras el lanzamiento el an\u0303o pasado en Sephora UK, la marca de belleza estara\u0301 disponible en exclusiva en Sephora Europa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/","og_locale":"es_ES","og_type":"article","og_title":"Haus Labs by Lady Gaga llega a Espa\u00f1a","og_description":"Tras el lanzamiento el an\u0303o pasado en Sephora UK, la marca de belleza estara\u0301 disponible en exclusiva en Sephora Europa.","og_url":"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/","og_site_name":"Grazia","article_modified_time":"2024-03-22T11:34:07+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/graziamagazine.com\/es\/wp-content\/uploads\/sites\/12\/2024\/03\/img-copia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/","url":"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/","name":"Haus Labs by Lady Gaga llega a Espa\u00f1a","isPartOf":{"@id":"https:\/\/graziamagazine.com\/es\/#website"},"datePublished":"2024-03-22T11:25:03+00:00","dateModified":"2024-03-22T11:34:07+00:00","description":"Tras el lanzamiento el an\u0303o pasado en Sephora UK, la marca de belleza estara\u0301 disponible en exclusiva en Sephora Europa.","breadcrumb":{"@id":"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/graziamagazine.com\/es\/articles\/haus-labs-by-lady-gaga-llega-a-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/graziamagazine.com\/es\/"},{"@type":"ListItem","position":2,"name":"Haus Labs by Lady Gaga llega a Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/graziamagazine.com\/es\/#website","url":"https:\/\/graziamagazine.com\/es\/","name":"Grazia","description":"Moda, belleza, celebrities, estilo de vida...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/graziamagazine.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Grazia","distributor_original_site_url":"https:\/\/graziamagazine.com\/es","push-errors":false,"_links":{"self":[{"href":"https:\/\/graziamagazine.com\/es\/wp-json\/wp\/v2\/articles\/175264"}],"collection":[{"href":"https:\/\/graziamagazine.com\/es\/wp-json\/wp\/v2\/articles"}],"about":[{"href":"https:\/\/graziamagazine.com\/es\/wp-json\/wp\/v2\/types\/articles"}],"author":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/es\/wp-json\/wp\/v2\/users\/11653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graziamagazine.com\/es\/wp-json\/wp\/v2\/media\/175265"}],"wp:attachment":[{"href":"https:\/\/graziamagazine.com\/es\/wp-json\/wp\/v2\/media?parent=175264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graziamagazine.com\/es\/wp-json\/wp\/v2\/categories?post=175264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}